{"id":34828,"date":"2026-09-02T10:31:35","date_gmt":"2026-09-02T08:31:35","guid":{"rendered":"https:\/\/www.cafelapalma.com\/?post_type=tribe_events&#038;p=34828"},"modified":"2026-09-02T10:32:17","modified_gmt":"2026-09-02T08:32:17","slug":"95club-sfhir-jaketi-dj-ese","status":"publish","type":"tribe_events","link":"https:\/\/www.cafelapalma.com\/en\/programacion\/95club-sfhir-jaketi-dj-ese\/","title":{"rendered":"95CLUB: SFHIR + JAKETI + DJ ESE"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t1  October\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t@\t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t23:59\t\t\t<\/span>\n\t\t\n\t\t\t<\/p>\n<\/div>\n\n\n<div  class=\"tribe-block tribe-block__event-price\" >\n\t\t\t<span class=\"tribe-block__event-price__cost\"> ENTRADA LIBRE <\/span>\n\t\t<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"832\" height=\"1040\" src=\"https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-832x1040.png\" alt=\"\" class=\"wp-image-34829\" srcset=\"https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-832x1040.png 832w, https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-240x300.png 240w, https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-767x959.png 767w, https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-10x12.png 10w, https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-48x60.png 48w, https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club.png 1122w\" sizes=\"auto, (max-width: 832px) 100vw, 832px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\"><strong>95Club<\/strong> evoca sus ra\u00edces en las raves ilegales de Detroit, cuando f\u00e1bricas abandonadas se convert\u00edan en templos sonoros y las m\u00e1quinas marcaban el pulso de una nueva identidad cultural.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Ser\u00e1 un refugio para quienes sienten el techno como cultura y comunidad<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Para esta ocasi\u00f3n bajaremos un poco los Bpms meti\u00e9ndonos de lleno en sonidos m\u00e1s electro, techno o idm&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Tendremos con nosotros un set lleno de fuerza, virtuosismo y mezclas imposibles con <strong>Djsfhir<\/strong>.\u00a0 Podremos disfrutar de un cl\u00e1sico del underground madrile\u00f1o,\u00a0 <strong>Dj Ese<\/strong> y de un set m\u00e1s mel\u00f3dico de lo habitual pero siempre fiel al techno de<strong> Jaketi<\/strong> .<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><a href=\"https:\/\/www.instagram.com\/sfhir?igsh=dmh2YTZhbXpteGly\"><em>Sigue a<\/em> <strong>Sfhir <\/strong><em>in <\/em><strong>Instagram<\/strong>.<\/a><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><a href=\"https:\/\/www.instagram.com\/zergio_mad?igsh=MXBtb2ZyeHZvdTZnOQ==\"><em>Sigue a<\/em> <strong>Dj Ese <\/strong><em>in <\/em><strong>Instagram<\/strong>.<\/a><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><a href=\"https:\/\/www.instagram.com\/jaketi?igsh=MW1pZTJ0dGwwZWUyYQ%3D%3D&amp;utm_source=qr\"><em>Sigue a<\/em> <strong>Jaketi <\/strong><em>in <\/em><strong>Instagram<\/strong>.<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n\n\t<div  class=\"tribe-block tribe-block__events-link\" >\n\t\t<div class=\"tribe-events tribe-common\">\n\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t\t\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\">\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--cal-export tribe-events-c-subscribe-dropdown__export-icon\" \taria-hidden=\"true\"\n\tviewbox=\"0 0 23 17\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.128.896V16.13c0 .211.145.383.323.383h15.354c.179 0 .323-.172.323-.383V.896c0-.212-.144-.383-.323-.383H.451C.273.513.128.684.128.896Zm16 6.742h-.901V4.679H1.009v10.729h14.218v-3.336h.901V7.638ZM1.01 1.614h14.218v2.058H1.009V1.614Z\" \/>\n\t<path d=\"M20.5 9.846H8.312M18.524 6.953l2.89 2.909-2.855 2.855\" stroke-width=\"1.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__button-text\"\n\t\t\t\t\t\t\taria-expanded=\"false\"\n\t\t\t\t\t\t\taria-controls=\"tribe-events-subscribe-dropdown-content\"\n\t\t\t\t\t\t\taria-label=\"View links to add events to your calendar\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tAdd to calendar\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\" \taria-hidden=\"true\"\n\tviewbox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"tribe-events-subscribe-dropdown-content\" class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--gcal\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;dates=20261001T235900\/20261001T235900&#038;text=95CLUB%3A%20SFHIR%20%2B%20JAKETI%20%2B%20DJ%20ESE&#038;details=%3Cdiv+class%3D%22wp-block-columns%22%3E%3Cdiv+class%3D%22wp-block-column%22+style%3D%22flex-basis%3A33.33%25%22%3E%3Cfigure+class%3D%22wp-block-image+size-large%22%3E%3Cimg+src%3D%22https%3A%2F%2Fwww.cafelapalma.com%2Fwp-content%2Fuploads%2F2026%2F09%2FCartel-La-Palma-95Club-832x1040.png%22+alt%3D%22%22+class%3D%22wp-image-34829%22%2F%3E%3C%2Ffigure%3E%3C%2Fdiv%3E%3Cdiv+class%3D%22wp-block-column%22+style%3D%22flex-basis%3A66.66%25%22%3E%3Cdiv+style%3D%22height%3A100px%22+aria-hidden%3D%22true%22+class%3D%22wp-block-spacer%22%3E%3C%2Fdiv%3E%3Cp+class%3D%22has-text-align-left%22%3E%3Cstrong%3E95Club%3C%2Fstrong%3E+evoca+sus+ra%C3%ADces+en+las+raves+ilegales+de+Detroit%2C+cuando+f%C3%A1bricas+abandonadas+se+convert%C3%ADan+en+templos+sonoros+y+las+m%C3%A1quinas+marcaban+el+pulso+de+una+nueva+identidad+cultural.%3C%2Fp%3E+%3Cp+class%3D%22has-text-align-left%22%3ESer%C3%A1+un+refugio+para+quienes+sienten+el+techno+como+cultura+y+comunidad%3C%2Fp%3E+%3Cp+class%3D%22has-text-align-left%22%3EPara+esta+ocasi%C3%B3n+bajaremos+un+poco+los+Bpms+meti%C3%A9ndonos+de+lleno+en+sonidos+m%C3%A1s+electro%2C+techno+o+idm%26nbsp%3B%3C%2Fp%3E+%3Cp+class%3D%22has-text-align-left%22%3ETendremos+con+nosotros+un+set+lleno%3C%2Fp%3E%3C%2Fdiv%3E%3C%2Fdiv%3E+%28View+Full+event+Description+Here%3A+https%3A%2F%2Fwww.cafelapalma.com%2Fen%2Fprogramacion%2F95club-sfhir-jaketi-dj-ese%2F%29&#038;trp=false&#038;ctz=Europe\/Madrid&#038;sprop=website:https:\/\/www.cafelapalma.com\/en\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tGoogle Calendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-365\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook 365\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-live\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook Live\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n<h2 class=\"tribe-block__related-events__title\">Related Events<\/h2>\n\n<ul  class=\"tribe-related-events tribe-clearfix\" >\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/www.cafelapalma.com\/en\/programacion\/fent-daboga-keruviin\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img loading=\"lazy\" decoding=\"async\" width=\"832\" height=\"1040\" src=\"https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/07\/cartel_concierto_03-09-832x1040.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/www.cafelapalma.com\/en\/programacion\/fent-daboga-keruviin\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tF\u20acNT + DABOGA + KERUVIIN\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">3  September@21:00<\/span><span class=\"tribe-event-time\">23:59<\/span><\/div>\n<\/li>\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/www.cafelapalma.com\/en\/programacion\/selected-layers-by-monkey-soul\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img loading=\"lazy\" decoding=\"async\" width=\"594\" height=\"1040\" src=\"https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/07\/pic1-e1785333628477-594x1040.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/www.cafelapalma.com\/en\/programacion\/selected-layers-by-monkey-soul\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\t\u00abSELECTED LAYERS\u00bb BY MONKEY SOUL\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">3  September@23:55<\/span><\/div>\n<\/li>\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/www.cafelapalma.com\/en\/programacion\/vertice-marta-canosa\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img loading=\"lazy\" decoding=\"async\" width=\"736\" height=\"1040\" src=\"https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/06\/Cartel_Vertice_Cafelapalma_Impresion_page-0001-1-736x1040.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/www.cafelapalma.com\/en\/programacion\/vertice-marta-canosa\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tV\u00c9RTICE + MARTA CANOSA\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">4  September@21:30<\/span><span class=\"tribe-event-time\">23:45<\/span><\/div>\n<\/li>\n\t<\/ul>","protected":false},"excerpt":{"rendered":"<p>95Club evoca sus ra\u00edces en las raves ilegales de Detroit, cuando f\u00e1bricas abandonadas se convert\u00edan en templos sonoros y las m\u00e1quinas marcaban el pulso de una nueva identidad cultural. Ser\u00e1 un refugio para quienes sienten el techno como cultura y comunidad Para esta ocasi\u00f3n bajaremos un poco los Bpms meti\u00e9ndonos de lleno en sonidos m\u00e1s &hellip; <\/p>","protected":false},"author":2,"featured_media":34829,"template":"","meta":{"_tec_requires_first_save":false,"_uag_custom_page_level_css":"","loftloader_page_shortcode":"","_EventAllDay":false,"_EventTimezone":"Europe\/Madrid","_EventStartDate":"2026-10-01 23:59:00","_EventEndDate":"2026-10-01 23:59:00","_EventStartDateUTC":"2026-10-01 21:59:00","_EventEndDateUTC":"2026-10-01 21:59:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"ENTRADA LIBRE","_EventCostDescription":"","_EventCurrencySymbol":"\u20ac","_EventCurrencyCode":"USD","_EventCurrencyPosition":"suffix","_EventDateTimeSeparator":"@","_EventTimeRangeSeparator":"-","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_ecp_custom_2":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[1363,9225,18819,18002,18617,9226,9227,18616],"tribe_events_cat":[],"class_list":["post-34828","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-cafe-la-palma","tag-cafe-la-palma-clubbing","tag-clubbing-gratis","tag-clubbing-malasana","tag-discoteca-gratis","tag-djs-madrid","tag-djs-malasana","tag-fiesta-gratis"],"uagb_featured_image_src":{"full":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club.png",1122,1402,false],"thumbnail":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-150x150.png",150,150,true],"medium":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-240x300.png",240,300,true],"medium_large":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-767x959.png",767,959,true],"large":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-832x1040.png",832,1040,true],"1536x1536":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club.png",1122,1402,false],"2048x2048":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club.png",1122,1402,false],"trp-custom-language-flag":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-10x12.png",10,12,true],"blossom-feminine-slider":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-1122x649.png",1122,649,true],"blossom-feminine-featured":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-1122x600.png",1122,600,true],"blossom-feminine-with-sidebar":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-1020x600.png",1020,600,true],"blossom-feminine-blog":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-435x435.png",435,435,true],"blossom-feminine-cat":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-450x300.png",450,300,true],"blossom-feminine-related":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-320x200.png",320,200,true],"blossom-feminine-schema":["https:\/\/www.cafelapalma.com\/wp-content\/uploads\/2026\/09\/Cartel-La-Palma-95Club-48x60.png",48,60,true]},"uagb_author_info":{"display_name":"Victor","author_link":"https:\/\/www.cafelapalma.com\/en\/author\/comunicacion\/"},"uagb_comment_info":0,"uagb_excerpt":"95Club evoca sus ra\u00edces en las raves ilegales de Detroit, cuando f\u00e1bricas abandonadas se convert\u00edan en templos sonoros y las m\u00e1quinas marcaban el pulso de una nueva identidad cultural. Ser\u00e1 un refugio para quienes sienten el techno como cultura y comunidad Para esta ocasi\u00f3n bajaremos un poco los Bpms meti\u00e9ndonos de lleno en sonidos m\u00e1s&hellip;","_links":{"self":[{"href":"https:\/\/www.cafelapalma.com\/en\/wp-json\/wp\/v2\/tribe_events\/34828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cafelapalma.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.cafelapalma.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.cafelapalma.com\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/www.cafelapalma.com\/en\/wp-json\/wp\/v2\/tribe_events\/34828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cafelapalma.com\/en\/wp-json\/wp\/v2\/media\/34829"}],"wp:attachment":[{"href":"https:\/\/www.cafelapalma.com\/en\/wp-json\/wp\/v2\/media?parent=34828"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cafelapalma.com\/en\/wp-json\/wp\/v2\/tags?post=34828"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.cafelapalma.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=34828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}